{"id":20617,"date":"2026-08-27T12:15:24","date_gmt":"2026-08-27T10:15:24","guid":{"rendered":"https:\/\/www.logisticauno.com\/?p=20617"},"modified":"2026-08-27T12:19:03","modified_gmt":"2026-08-27T10:19:03","slug":"larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030","status":"publish","type":"post","link":"https:\/\/www.logisticauno.com\/en\/larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030\/","title":{"rendered":"L&#8217;Arena: sostenibilit\u00e0 e crescita in Logistica Uno verso il 2030"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"20617\" class=\"elementor elementor-20617\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-222ecc6 e-flex e-con-boxed e-con e-parent\" data-id=\"222ecc6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-555d349 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"555d349\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">L&#8217;Arena: sostenibilit\u00e0 e crescita in Logistica Uno verso il 2030<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3eaacac e-flex e-con-boxed e-con e-parent\" data-id=\"3eaacac\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7608f8b e-con-full e-flex e-con e-child\" data-id=\"7608f8b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b64923b elementor-widget elementor-widget-image\" data-id=\"b64923b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"656\" src=\"https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/08\/arena-1.png\" class=\"attachment-large size-large wp-image-20618\" alt=\"\" srcset=\"https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/08\/arena-1.png 936w, https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/08\/arena-1-300x246.png 300w, https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/08\/arena-1-768x629.png 768w, https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/08\/arena-1-15x12.png 15w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01b4c92 elementor-widget elementor-widget-image\" data-id=\"01b4c92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"498\" src=\"https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/08\/arena-2.png\" class=\"attachment-large size-large wp-image-20619\" alt=\"\" srcset=\"https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/08\/arena-2.png 943w, https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/08\/arena-2-300x187.png 300w, https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/08\/arena-2-768x478.png 768w, https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/08\/arena-2-18x12.png 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fe6015 elementor-widget elementor-widget-text-editor\" data-id=\"1fe6015\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>\u00a0<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-38a364e e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"38a364e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9c8e887 elementor-widget elementor-widget-heading\" data-id=\"9c8e887\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Related news<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-708fc22 elementor-grid-1 elementor-posts--thumbnail-left elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-posts\" data-id=\"708fc22\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;10&quot;,&quot;sizes&quot;:[]},&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20596 post type-post status-publish format-standard has-post-thumbnail hentry category-news\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.logisticauno.com\/en\/logistica-uno-alla-green-planet-cup-2026\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-06-12-at-09.32.14-1-225x300.jpeg\" class=\"attachment-medium size-medium wp-image-20597\" alt=\"\" srcset=\"https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-06-12-at-09.32.14-1-225x300.jpeg 225w, https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-06-12-at-09.32.14-1-768x1024.jpeg 768w, https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-06-12-at-09.32.14-1-1152x1536.jpeg 1152w, https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-06-12-at-09.32.14-1-9x12.jpeg 9w, https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-06-12-at-09.32.14-1.jpeg 1536w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.logisticauno.com\/en\/logistica-uno-alla-green-planet-cup-2026\/\" >\n\t\t\t\tLogistica Uno alla Green Planet Cup 2026\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t6 July 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.logisticauno.com\/en\/logistica-uno-alla-green-planet-cup-2026\/\" aria-label=\"Read more about Logistica Uno alla Green Planet Cup 2026\" tabindex=\"-1\" >\n\t\t\tRead More &#034;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20590 post type-post status-publish format-standard has-post-thumbnail hentry category-news\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.logisticauno.com\/en\/logistica-uno-sostiene-progetto-quid-un-investimento-concreto-nelle-persone\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"300\" src=\"https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/07\/Template-Ticket-Campagna-A-Ticket-to-a-Bigger-Future-4_5-240x300.png\" class=\"attachment-medium size-medium wp-image-20591\" alt=\"\" srcset=\"https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/07\/Template-Ticket-Campagna-A-Ticket-to-a-Bigger-Future-4_5-240x300.png 240w, https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/07\/Template-Ticket-Campagna-A-Ticket-to-a-Bigger-Future-4_5-819x1024.png 819w, https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/07\/Template-Ticket-Campagna-A-Ticket-to-a-Bigger-Future-4_5-768x960.png 768w, https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/07\/Template-Ticket-Campagna-A-Ticket-to-a-Bigger-Future-4_5-10x12.png 10w, https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/07\/Template-Ticket-Campagna-A-Ticket-to-a-Bigger-Future-4_5.png 1080w\" sizes=\"(max-width: 240px) 100vw, 240px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.logisticauno.com\/en\/logistica-uno-sostiene-progetto-quid-un-investimento-concreto-nelle-persone\/\" >\n\t\t\t\tLogistica Uno sostiene Progetto Quid: un investimento concreto nelle persone\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t6 July 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.logisticauno.com\/en\/logistica-uno-sostiene-progetto-quid-un-investimento-concreto-nelle-persone\/\" aria-label=\"Read more about Logistica Uno sostiene Progetto Quid: un investimento concreto nelle persone\" tabindex=\"-1\" >\n\t\t\tRead More &#034;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20585 post type-post status-publish format-standard has-post-thumbnail hentry category-news\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.logisticauno.com\/en\/logistica-uno-a-sostegno-di-santa-maria-del-cammino\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-04-21-at-11.54.09-300x225.jpeg\" class=\"attachment-medium size-medium wp-image-20567\" alt=\"\" srcset=\"https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-04-21-at-11.54.09-300x225.jpeg 300w, https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-04-21-at-11.54.09-1024x768.jpeg 1024w, https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-04-21-at-11.54.09-768x576.jpeg 768w, https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-04-21-at-11.54.09-1536x1152.jpeg 1536w, https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-04-21-at-11.54.09-16x12.jpeg 16w, https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-04-21-at-11.54.09.jpeg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.logisticauno.com\/en\/logistica-uno-a-sostegno-di-santa-maria-del-cammino\/\" >\n\t\t\t\tLogistica Uno a sostegno di Santa Maria del Cammino\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t6 July 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.logisticauno.com\/en\/logistica-uno-a-sostegno-di-santa-maria-del-cammino\/\" aria-label=\"Read more about Logistica Uno a sostegno di Santa Maria del Cammino\" tabindex=\"-1\" >\n\t\t\tRead More &#034;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20562 post type-post status-publish format-standard has-post-thumbnail hentry category-news\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.logisticauno.com\/en\/logistica-uno-allo-speak-dating-di-confindustria-sullai\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"199\" src=\"https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/07\/Immagine-2026-07-06-142842-300x199.png\" class=\"attachment-medium size-medium wp-image-20580\" alt=\"\" srcset=\"https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/07\/Immagine-2026-07-06-142842-300x199.png 300w, https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/07\/Immagine-2026-07-06-142842-18x12.png 18w, https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/07\/Immagine-2026-07-06-142842.png 747w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.logisticauno.com\/en\/logistica-uno-allo-speak-dating-di-confindustria-sullai\/\" >\n\t\t\t\tLogistica Uno allo Speak Dating di Confindustria sull&#8217;AI\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t6 July 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.logisticauno.com\/en\/logistica-uno-allo-speak-dating-di-confindustria-sullai\/\" aria-label=\"Read more about Logistica Uno allo Speak Dating di Confindustria sull&#8217;AI\" tabindex=\"-1\" >\n\t\t\tRead More &#034;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20485 post type-post status-publish format-standard has-post-thumbnail hentry category-news\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.logisticauno.com\/en\/intervista-a-riccardo-wagner-adhoc-group\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-18-at-10.27.54-300x225.jpeg\" class=\"attachment-medium size-medium wp-image-20486\" alt=\"Intervista a Riccardo Wagner \u2013 AdHoc Group\" srcset=\"https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-18-at-10.27.54-300x225.jpeg 300w, https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-18-at-10.27.54-1024x768.jpeg 1024w, https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-18-at-10.27.54-768x576.jpeg 768w, https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-18-at-10.27.54-1536x1152.jpeg 1536w, https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-18-at-10.27.54-16x12.jpeg 16w, https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-18-at-10.27.54.jpeg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.logisticauno.com\/en\/intervista-a-riccardo-wagner-adhoc-group\/\" >\n\t\t\t\tIntervista a Riccardo Wagner \u2013 AdHoc Group\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t26 May 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.logisticauno.com\/en\/intervista-a-riccardo-wagner-adhoc-group\/\" aria-label=\"Read more about Intervista a Riccardo Wagner \u2013 AdHoc Group\" tabindex=\"-1\" >\n\t\t\tRead More &#034;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9d3ee6d e-flex e-con-boxed e-con e-parent\" data-id=\"9d3ee6d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a8d2878 e-con-full e-flex e-con e-child\" data-id=\"a8d2878\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f117938 e-con-full e-flex e-con e-child\" data-id=\"f117938\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f7defc2 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"f7defc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.logisticauno.com\/en\/news\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">BACK TO NEWS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-725cfe5 e-con-full e-flex e-con e-child\" data-id=\"725cfe5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f165a6e e-flex e-con-boxed e-con e-parent\" data-id=\"f165a6e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1f12b6b e-con-full e-flex e-con e-child\" data-id=\"1f12b6b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-96d61e4 elementor-post-navigation-borders-yes elementor-widget elementor-widget-post-navigation\" data-id=\"96d61e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-navigation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-post-navigation\" role=\"navigation\" aria-label=\"Post Navigation\">\n\t\t\t<div class=\"elementor-post-navigation__prev elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/www.logisticauno.com\/en\/logistica-uno-a-tuttofood-2026\/\" rel=\"prev\"><span class=\"elementor-post-navigation__link__prev\"><span class=\"post-navigation__prev--label\">Previous article<\/span><span class=\"post-navigation__prev--title\">Logistica Uno a TUTTOFOOD 2026<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-post-navigation__separator-wrapper\">\n\t\t\t\t\t<div class=\"elementor-post-navigation__separator\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-post-navigation__next elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/www.logisticauno.com\/en\/logistica-uno-allo-speak-dating-di-confindustria-sullai\/\" rel=\"next\"><span class=\"elementor-post-navigation__link__next\"><span class=\"post-navigation__next--label\">Next article<\/span><span class=\"post-navigation__next--title\">Logistica Uno allo Speak Dating di Confindustria sull&#8217;AI<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u00a0 News correlate TORNA ALLE NEWS<\/p>","protected":false},"author":3,"featured_media":20618,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[135],"tags":[],"class_list":["post-20617","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-stampa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;Arena: sostenibilit\u00e0 e crescita in Logistica Uno verso il 2030 - Logistica Uno<\/title>\n<meta name=\"description\" content=\"Logistica Uno nel nuovo numero de &#039;Il Finanziere&#039; parla di innovazione e tecnologia soffermandosi su efficienza e supply chain evoluta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.logisticauno.com\/en\/larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;Arena: sostenibilit\u00e0 e crescita in Logistica Uno verso il 2030 - Logistica Uno\" \/>\n<meta property=\"og:description\" content=\"Logistica Uno nel nuovo numero de &#039;Il Finanziere&#039; parla di innovazione e tecnologia soffermandosi su efficienza e supply chain evoluta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.logisticauno.com\/en\/larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030\/\" \/>\n<meta property=\"og:site_name\" content=\"Logistica Uno\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/logisticauno\" \/>\n<meta property=\"article:published_time\" content=\"2026-08-27T10:15:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-27T10:19:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/08\/arena-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"936\" \/>\n\t<meta property=\"og:image:height\" content=\"767\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"LogisticaUno LogisticaUno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"LogisticaUno LogisticaUno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.logisticauno.com\\\/larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.logisticauno.com\\\/larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030\\\/\"},\"author\":{\"name\":\"LogisticaUno LogisticaUno\",\"@id\":\"https:\\\/\\\/www.logisticauno.com\\\/#\\\/schema\\\/person\\\/12dcb6aabf2586772e3e29f2215ff945\"},\"headline\":\"L&#8217;Arena: sostenibilit\u00e0 e crescita in Logistica Uno verso il 2030\",\"datePublished\":\"2026-08-27T10:15:24+00:00\",\"dateModified\":\"2026-08-27T10:19:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.logisticauno.com\\\/larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030\\\/\"},\"wordCount\":14,\"publisher\":{\"@id\":\"https:\\\/\\\/www.logisticauno.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.logisticauno.com\\\/larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.logisticauno.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/arena-1.png\",\"articleSection\":[\"Stampa\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.logisticauno.com\\\/larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030\\\/\",\"url\":\"https:\\\/\\\/www.logisticauno.com\\\/larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030\\\/\",\"name\":\"L'Arena: sostenibilit\u00e0 e crescita in Logistica Uno verso il 2030 - Logistica Uno\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.logisticauno.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.logisticauno.com\\\/larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.logisticauno.com\\\/larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.logisticauno.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/arena-1.png\",\"datePublished\":\"2026-08-27T10:15:24+00:00\",\"dateModified\":\"2026-08-27T10:19:03+00:00\",\"description\":\"Logistica Uno nel nuovo numero de 'Il Finanziere' parla di innovazione e tecnologia soffermandosi su efficienza e supply chain evoluta.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.logisticauno.com\\\/larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.logisticauno.com\\\/larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.logisticauno.com\\\/larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.logisticauno.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/arena-1.png\",\"contentUrl\":\"https:\\\/\\\/www.logisticauno.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/arena-1.png\",\"width\":936,\"height\":767},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.logisticauno.com\\\/larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.logisticauno.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;Arena: sostenibilit\u00e0 e crescita in Logistica Uno verso il 2030\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.logisticauno.com\\\/#website\",\"url\":\"https:\\\/\\\/www.logisticauno.com\\\/\",\"name\":\"Logistica Uno\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.logisticauno.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.logisticauno.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.logisticauno.com\\\/#organization\",\"name\":\"Logistica Uno\",\"url\":\"https:\\\/\\\/www.logisticauno.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.logisticauno.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.logisticauno.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo-vettoriale.png\",\"contentUrl\":\"https:\\\/\\\/www.logisticauno.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo-vettoriale.png\",\"width\":169,\"height\":50,\"caption\":\"Logistica Uno\"},\"image\":{\"@id\":\"https:\\\/\\\/www.logisticauno.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/logisticauno\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.logisticauno.com\\\/#\\\/schema\\\/person\\\/12dcb6aabf2586772e3e29f2215ff945\",\"name\":\"LogisticaUno LogisticaUno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a24c42cdd722d694b7b0d5134134bd32c2776a7a0e73b420c6ccd051a76575ba?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a24c42cdd722d694b7b0d5134134bd32c2776a7a0e73b420c6ccd051a76575ba?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a24c42cdd722d694b7b0d5134134bd32c2776a7a0e73b420c6ccd051a76575ba?s=96&d=mm&r=g\",\"caption\":\"LogisticaUno LogisticaUno\"},\"url\":\"https:\\\/\\\/www.logisticauno.com\\\/en\\\/author\\\/logisticaunoeurope\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'Arena: sostenibilit\u00e0 e crescita in Logistica Uno verso il 2030 - Logistica Uno","description":"Logistica Uno nel nuovo numero de 'Il Finanziere' parla di innovazione e tecnologia soffermandosi su efficienza e supply chain evoluta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.logisticauno.com\/en\/larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030\/","og_locale":"en_GB","og_type":"article","og_title":"L'Arena: sostenibilit\u00e0 e crescita in Logistica Uno verso il 2030 - Logistica Uno","og_description":"Logistica Uno nel nuovo numero de 'Il Finanziere' parla di innovazione e tecnologia soffermandosi su efficienza e supply chain evoluta.","og_url":"https:\/\/www.logisticauno.com\/en\/larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030\/","og_site_name":"Logistica Uno","article_publisher":"https:\/\/www.facebook.com\/logisticauno","article_published_time":"2026-08-27T10:15:24+00:00","article_modified_time":"2026-08-27T10:19:03+00:00","og_image":[{"width":936,"height":767,"url":"https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/08\/arena-1.png","type":"image\/png"}],"author":"LogisticaUno LogisticaUno","twitter_card":"summary_large_image","twitter_misc":{"Written by":"LogisticaUno LogisticaUno","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.logisticauno.com\/larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030\/#article","isPartOf":{"@id":"https:\/\/www.logisticauno.com\/larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030\/"},"author":{"name":"LogisticaUno LogisticaUno","@id":"https:\/\/www.logisticauno.com\/#\/schema\/person\/12dcb6aabf2586772e3e29f2215ff945"},"headline":"L&#8217;Arena: sostenibilit\u00e0 e crescita in Logistica Uno verso il 2030","datePublished":"2026-08-27T10:15:24+00:00","dateModified":"2026-08-27T10:19:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.logisticauno.com\/larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030\/"},"wordCount":14,"publisher":{"@id":"https:\/\/www.logisticauno.com\/#organization"},"image":{"@id":"https:\/\/www.logisticauno.com\/larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030\/#primaryimage"},"thumbnailUrl":"https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/08\/arena-1.png","articleSection":["Stampa"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.logisticauno.com\/larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030\/","url":"https:\/\/www.logisticauno.com\/larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030\/","name":"L'Arena: sostenibilit\u00e0 e crescita in Logistica Uno verso il 2030 - Logistica Uno","isPartOf":{"@id":"https:\/\/www.logisticauno.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.logisticauno.com\/larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030\/#primaryimage"},"image":{"@id":"https:\/\/www.logisticauno.com\/larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030\/#primaryimage"},"thumbnailUrl":"https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/08\/arena-1.png","datePublished":"2026-08-27T10:15:24+00:00","dateModified":"2026-08-27T10:19:03+00:00","description":"Logistica Uno nel nuovo numero de 'Il Finanziere' parla di innovazione e tecnologia soffermandosi su efficienza e supply chain evoluta.","breadcrumb":{"@id":"https:\/\/www.logisticauno.com\/larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.logisticauno.com\/larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.logisticauno.com\/larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030\/#primaryimage","url":"https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/08\/arena-1.png","contentUrl":"https:\/\/www.logisticauno.com\/wp-content\/uploads\/2026\/08\/arena-1.png","width":936,"height":767},{"@type":"BreadcrumbList","@id":"https:\/\/www.logisticauno.com\/larena-sostenibilita-e-crescita-in-logistica-uno-verso-il-2030\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.logisticauno.com\/"},{"@type":"ListItem","position":2,"name":"L&#8217;Arena: sostenibilit\u00e0 e crescita in Logistica Uno verso il 2030"}]},{"@type":"WebSite","@id":"https:\/\/www.logisticauno.com\/#website","url":"https:\/\/www.logisticauno.com\/","name":"Logistica Uno","description":"","publisher":{"@id":"https:\/\/www.logisticauno.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.logisticauno.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.logisticauno.com\/#organization","name":"Logistica Uno","url":"https:\/\/www.logisticauno.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.logisticauno.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.logisticauno.com\/wp-content\/uploads\/2024\/01\/logo-vettoriale.png","contentUrl":"https:\/\/www.logisticauno.com\/wp-content\/uploads\/2024\/01\/logo-vettoriale.png","width":169,"height":50,"caption":"Logistica Uno"},"image":{"@id":"https:\/\/www.logisticauno.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/logisticauno"]},{"@type":"Person","@id":"https:\/\/www.logisticauno.com\/#\/schema\/person\/12dcb6aabf2586772e3e29f2215ff945","name":"LogisticaUno LogisticaUno","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/a24c42cdd722d694b7b0d5134134bd32c2776a7a0e73b420c6ccd051a76575ba?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a24c42cdd722d694b7b0d5134134bd32c2776a7a0e73b420c6ccd051a76575ba?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a24c42cdd722d694b7b0d5134134bd32c2776a7a0e73b420c6ccd051a76575ba?s=96&d=mm&r=g","caption":"LogisticaUno LogisticaUno"},"url":"https:\/\/www.logisticauno.com\/en\/author\/logisticaunoeurope\/"}]}},"_links":{"self":[{"href":"https:\/\/www.logisticauno.com\/en\/wp-json\/wp\/v2\/posts\/20617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.logisticauno.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.logisticauno.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.logisticauno.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.logisticauno.com\/en\/wp-json\/wp\/v2\/comments?post=20617"}],"version-history":[{"count":4,"href":"https:\/\/www.logisticauno.com\/en\/wp-json\/wp\/v2\/posts\/20617\/revisions"}],"predecessor-version":[{"id":20624,"href":"https:\/\/www.logisticauno.com\/en\/wp-json\/wp\/v2\/posts\/20617\/revisions\/20624"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.logisticauno.com\/en\/wp-json\/wp\/v2\/media\/20618"}],"wp:attachment":[{"href":"https:\/\/www.logisticauno.com\/en\/wp-json\/wp\/v2\/media?parent=20617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.logisticauno.com\/en\/wp-json\/wp\/v2\/categories?post=20617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.logisticauno.com\/en\/wp-json\/wp\/v2\/tags?post=20617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}